{"id":12821,"date":"2015-11-03T11:15:10","date_gmt":"2015-11-03T11:15:10","guid":{"rendered":"http:\/\/nandabalieiro.com.br\/blog\/?p=12821"},"modified":"2015-11-04T10:45:35","modified_gmt":"2015-11-04T10:45:35","slug":"a-arvore-do-nosso-primeiro-natal","status":"publish","type":"post","link":"https:\/\/nandabalieiro.com.br\/blog\/2015\/11\/a-arvore-do-nosso-primeiro-natal\/","title":{"rendered":"A \u00e1rvore do nosso (primeiro) Natal\u00a0"},"content":{"rendered":"<p><a href=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/DSC7548.jpg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-12826\" src=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/DSC7548-1024x680.jpg\" alt=\"_DSC7548\" width=\"720\" height=\"478\" srcset=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/DSC7548-1024x680.jpg 1024w, https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/DSC7548-300x199.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Em 2010, quando nos mudamos para o nosso primeiro ap\u00ea, eu fiz quest\u00e3o de comprar uma \u00e1rvore de natal. Mudamos no final do ano e eu queria MUITO enfeitar a casa. <a href=\"https:\/\/nandabalieiro.com.br\/blog\/2010\/11\/tbbt-hp-arvore-de-natal\/\" target=\"_blank\">Compramos uma \u00e1rvore pequena<\/a>, magrela, e montei. Montei sozinha porque o Bruno n\u00e3o <del>liga<\/del> ligava nada pra essas coisas. Ela ficou meio estranha, apesar dos enfeites bonitos que comprei. Mesmo assim fiquei feliz. Na casa dos meus pais\u00a0nunca teve \u00e1rvore de natal, presentes embaixo\u00a0da \u00e1rvore, esse clima gostoso que essa \u00e9poca do ano traz. N\u00f3s pass\u00e1vamos o natal na casa da minha av\u00f3, ent\u00e3o era s\u00f3 l\u00e1 que eu via enfeites.<\/p>\n<p style=\"text-align: justify;\">Mas esse ano, tudo ser\u00e1 (j\u00e1 est\u00e1 sendo) diferente. Esse ano temos uma pituca que eu quero que cres\u00e7a com direito a muitas boas lembran\u00e7as dessa \u00e9poca do ano. E n\u00e3o digo isso pelos presentes n\u00e3o, digo pelas tradi\u00e7\u00f5es que iremos fazer\u00a0juntos. Como fam\u00edlia.<\/p>\n<p style=\"text-align: justify;\">Compramos nossa \u00e1rvore na segunda feira passada (feriado). Eu queria uma \u00e1rvore grande e gordinha, pra ficar linda. Compramos mais algumas bolas e estrelas para enfeit\u00e1-la. Bruno me ajudou em tudo (ali\u00e1s, foi ele quem montou depois de ver que eu estava procurando um tutorial na internet para enfeitar a \u00e1rvore &#8211; n\u00e3o me julguem eu sou p\u00e9ssima para essas coisas rs). Coloquei m\u00fasicas natalinas para entrarmos no clima. Clarice ficou no ch\u00e3o, ora olhava, ora mordia algum brinquedo rs Ainda n\u00e3o entende o que \u00e9 tudo isso, claro, mas nos pr\u00f3ximos anos ela vai participar da montagem da \u00e1rvore e vai ser ainda mais gostoso.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/IMG_8233.jpg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-12832\" src=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/IMG_8233-1024x1024.jpg\" alt=\"IMG_8233\" width=\"720\" height=\"720\" srcset=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/IMG_8233-1024x1024.jpg 1024w, https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/IMG_8233-300x300.jpg 300w, https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/IMG_8233-160x160.jpg 160w, https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/IMG_8233-320x320.jpg 320w, https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/IMG_8233.jpg 1936w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em>Antes e depois da nossa \u00e1rvore<\/em><\/p>\n<p style=\"text-align: justify;\">Hoje em dia minha m\u00e3e adora enfeites, acho que compensa a \u00e9poca que a gente n\u00e3o tinha muita condi\u00e7\u00e3o de gastar dinheiro com isso. Ela tem os\u00a0enfeites mais lindos que j\u00e1 vi. E ela me deu um papai noel que faz a contagem regressiva para o natal. J\u00e1 coloquei ele no seu devido lugar. Fico imaginando a\u00a0Clarice mudando os dias daqui alguns anos, doida pra que chegue logo a noite feliz.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/IMG_8218.jpg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-12834\" src=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/IMG_8218-768x1024.jpg\" alt=\"IMG_8218\" width=\"720\" height=\"960\" srcset=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/IMG_8218-768x1024.jpg 768w, https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/IMG_8218-225x300.jpg 225w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ainda quero\u00a0colocar o enfeite na porta no apartamento e mais alguns detalhes em casa. Minha m\u00e3e me disse que separou tamb\u00e9m outras coisinhas. Vamos deixar tudo lindo para essa \u00e9poca linda do ano. Que venha o primeiro natal da Clarice (fora da barriga n\u00e9 rs). Ela j\u00e1 est\u00e1 no clima!<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/DSC7562.jpg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-12828\" src=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/DSC7562-1024x680.jpg\" alt=\"_DSC7562\" width=\"720\" height=\"478\" srcset=\"https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/DSC7562-1024x680.jpg 1024w, https:\/\/nandabalieiro.com.br\/blog\/wp-content\/uploads\/2015\/11\/DSC7562-300x199.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 2010, quando nos mudamos para o nosso primeiro ap\u00ea, eu fiz quest\u00e3o de comprar uma \u00e1rvore de natal. Mudamos no final do ano e eu queria MUITO enfeitar a casa. Compramos uma \u00e1rvore pequena, magrela, e montei. Montei sozinha&#8230;<\/p>\n","protected":false},"author":1,"featured_media":12828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[195],"tags":[56],"_links":{"self":[{"href":"https:\/\/nandabalieiro.com.br\/blog\/wp-json\/wp\/v2\/posts\/12821"}],"collection":[{"href":"https:\/\/nandabalieiro.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nandabalieiro.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nandabalieiro.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nandabalieiro.com.br\/blog\/wp-json\/wp\/v2\/comments?post=12821"}],"version-history":[{"count":4,"href":"https:\/\/nandabalieiro.com.br\/blog\/wp-json\/wp\/v2\/posts\/12821\/revisions"}],"predecessor-version":[{"id":12836,"href":"https:\/\/nandabalieiro.com.br\/blog\/wp-json\/wp\/v2\/posts\/12821\/revisions\/12836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nandabalieiro.com.br\/blog\/wp-json\/wp\/v2\/media\/12828"}],"wp:attachment":[{"href":"https:\/\/nandabalieiro.com.br\/blog\/wp-json\/wp\/v2\/media?parent=12821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nandabalieiro.com.br\/blog\/wp-json\/wp\/v2\/categories?post=12821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nandabalieiro.com.br\/blog\/wp-json\/wp\/v2\/tags?post=12821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}